{"id":108,"count":4,"description":"","link":"https:\/\/helloschool.be\/fr\/blog\/category\/helloschool-be-fr\/","name":"Helloschool.be","slug":"helloschool-be-fr","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Helloschool.be Archieven - Helloschool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helloschool.be Archieven - Helloschool\" \/>\n<meta property=\"og:url\" content=\"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/\" \/>\n<meta property=\"og:site_name\" content=\"Helloschool\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/blog\\\/category\\\/helloschool-be\\\/\",\"url\":\"https:\\\/\\\/helloschool.be\\\/blog\\\/category\\\/helloschool-be\\\/\",\"name\":\"Helloschool.be Archieven - Helloschool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloschool.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/helloschool.be\\\/blog\\\/category\\\/helloschool-be\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/blog\\\/category\\\/helloschool-be\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Helloschool.be\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/#website\",\"url\":\"https:\\\/\\\/helloschool.be\\\/\",\"name\":\"Helloschool\",\"description\":\"Concentrez-vous sur l\u2019enseignement, nous nous occupons du reste.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/helloschool.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Helloschool.be Archieven - Helloschool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/","og_locale":"fr_FR","og_type":"article","og_title":"Helloschool.be Archieven - Helloschool","og_url":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/","og_site_name":"Helloschool","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/","url":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/","name":"Helloschool.be Archieven - Helloschool","isPartOf":{"@id":"https:\/\/helloschool.be\/#website"},"breadcrumb":{"@id":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/helloschool.be\/blog\/category\/helloschool-be\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/helloschool.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Helloschool.be"}]},{"@type":"WebSite","@id":"https:\/\/helloschool.be\/#website","url":"https:\/\/helloschool.be\/","name":"Helloschool","description":"Concentrez-vous sur l\u2019enseignement, nous nous occupons du reste.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/helloschool.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/categories\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/posts?categories=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}