{"id":124,"count":9,"description":"","link":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/","name":"\u00c0 l&#039;\u00e9cole","slug":"a-lecole","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 l&#039;\u00e9cole Archieven - Helloschool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 l&#039;\u00e9cole Archieven - Helloschool\" \/>\n<meta property=\"og:url\" content=\"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/\" \/>\n<meta property=\"og:site_name\" content=\"Helloschool\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/categorie\\\/a-lecole\\\/\",\"url\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/categorie\\\/a-lecole\\\/\",\"name\":\"\u00c0 l&#039;\u00e9cole Archieven - Helloschool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/helloschool.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/categorie\\\/a-lecole\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/categorie\\\/a-lecole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/helloschool.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 l&#039;\u00e9cole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/helloschool.be\\\/#website\",\"url\":\"https:\\\/\\\/helloschool.be\\\/\",\"name\":\"Helloschool\",\"description\":\"Concentrez-vous sur l\u2019enseignement, nous nous occupons du reste.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/helloschool.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 l&#039;\u00e9cole Archieven - Helloschool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 l&#039;\u00e9cole Archieven - Helloschool","og_url":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/","og_site_name":"Helloschool","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/","url":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/","name":"\u00c0 l&#039;\u00e9cole Archieven - Helloschool","isPartOf":{"@id":"https:\/\/helloschool.be\/#website"},"breadcrumb":{"@id":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/helloschool.be\/fr\/categorie\/a-lecole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/helloschool.be\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 l&#039;\u00e9cole"}]},{"@type":"WebSite","@id":"https:\/\/helloschool.be\/#website","url":"https:\/\/helloschool.be\/","name":"Helloschool","description":"Concentrez-vous sur l\u2019enseignement, nous nous occupons du reste.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/helloschool.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/product_cat\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/helloschool.be\/fr\/wp-json\/wp\/v2\/product?product_cat=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}